{"id":4592,"count":1,"description":"","link":"https:\/\/www.mp3poolonline.com\/blog\/tag\/celebrity-birthday-party\/","name":"Celebrity birthday party","slug":"celebrity-birthday-party","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.mp3poolonline.com\/blog\/wp-json\/wp\/v2\/tags\/4592"}],"collection":[{"href":"https:\/\/www.mp3poolonline.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.mp3poolonline.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.mp3poolonline.com\/blog\/wp-json\/wp\/v2\/posts?tags=4592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}